{"id":20851,"date":"2016-12-07T12:12:01","date_gmt":"2016-12-07T11:12:01","guid":{"rendered":"http:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1.jpg"},"modified":"2017-01-17T16:12:53","modified_gmt":"2017-01-17T15:12:53","slug":"viva-life-style-and-travel-1-2","status":"inherit","type":"attachment","link":"https:\/\/www.hayariparis.com\/en\/%e4%ba%9a%e6%b4%b2%e6%9d%83%e5%a8%81%e9%a6%99%e6%b0%b4%e6%9d%82%e5%bf%97%e5%93%81%e7%89%8chayari-parfums-paris\/viva-life-style-and-travel-1-2\/","title":{"rendered":"Viva life style and travel 1"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-20851","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"166\" src=\"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-300x199.jpg 300w, https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-768x509.jpg 768w, https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-1024x679.jpg 1024w, https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1.jpg 1233w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Viva Lifestyle and Travel<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1233,"height":817,"file":"2016\/12\/Viva-life-style-and-travel-1.jpg","sizes":{"thumbnail":{"file":"Viva-life-style-and-travel-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-150x150.jpg"},"medium":{"file":"Viva-life-style-and-travel-1-300x199.jpg","width":300,"height":199,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-300x199.jpg"},"medium_large":{"file":"Viva-life-style-and-travel-1-768x509.jpg","width":768,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-768x509.jpg"},"large":{"file":"Viva-life-style-and-travel-1-1024x679.jpg","width":1024,"height":679,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-1024x679.jpg"},"post-thumb-big":{"file":"Viva-life-style-and-travel-1-1140x640.jpg","width":1140,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-1140x640.jpg"},"shop-thumb":{"file":"Viva-life-style-and-travel-1-290x370.jpg","width":290,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-290x370.jpg"},"shop-thumb-main":{"file":"Viva-life-style-and-travel-1-555x710.jpg","width":555,"height":710,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-555x710.jpg"},"shop-thumb-2":{"file":"Viva-life-style-and-travel-1-70x90.jpg","width":70,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-70x90.jpg"},"shop-category-thumb":{"file":"Viva-life-style-and-travel-1-320x256.jpg","width":320,"height":256,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-320x256.jpg"},"shop_thumbnail":{"file":"Viva-life-style-and-travel-1-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-180x180.jpg"},"shop_catalog":{"file":"Viva-life-style-and-travel-1-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-300x300.jpg"},"shop_single":{"file":"Viva-life-style-and-travel-1-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1-600x600.jpg"},"full":{"file":"Viva-life-style-and-travel-1.jpg","width":1233,"height":817,"mime_type":"image\/jpeg","source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3731,"source_url":"https:\/\/www.hayariparis.com\/wp-content\/uploads\/2016\/12\/Viva-life-style-and-travel-1.jpg","filename":"Viva-life-style-and-travel-1.jpg","filesize":118885,"_links":{"self":[{"href":"https:\/\/www.hayariparis.com\/en\/wp-json\/wp\/v2\/media\/20851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hayariparis.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.hayariparis.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.hayariparis.com\/en\/wp-json\/wp\/v2\/users\/5"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3731,"href":"https:\/\/www.hayariparis.com\/en\/wp-json\/wp\/v2\/posts\/3731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}